{"id":136,"date":"2023-08-10T12:39:24","date_gmt":"2023-08-10T12:39:24","guid":{"rendered":"https:\/\/motolumino.com\/?page_id=136"},"modified":"2023-10-03T13:42:31","modified_gmt":"2023-10-03T13:42:31","slug":"contact","status":"publish","type":"page","link":"https:\/\/motolumino.com\/fr\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;gcid-73c13341-f07f-4720-b77d-a4e55228eaff&#8221; global_colors_info=&#8221;{%22gcid-73c13341-f07f-4720-b77d-a4e55228eaff%22:%91%22background_color%22%93}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_font_size=&#8221;17px&#8221; header_text_color=&#8221;#000000&#8243; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221; text_letter_spacing__hover_enabled=&#8221;on|desktop&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Contact us<\/h1>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#000000&#8243; divider_weight=&#8221;2px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;17%&#8221; max_width=&#8221;77%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;5px|5px|5px|5px|true|true&#8221; custom_padding=&#8221;5px|5px|5px|5px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; text_letter_spacing=&#8221;0.5px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6 style=\"text-align: center;\"><span>Leave your message here and we will reply to you shortly<\/span><\/h6>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=&#8221;on&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;71%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<style id=\"wpforms-css-vars-536\">\n\t\t\t\t#wpforms-536 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style>\r\n<style type=\"text\/css\">\r\n@import url('https:\/\/fonts.googleapis.com\/css?family=Roboto');\r\n\r\n\r\nbody #wpforms-536 {\r\n\t\tbackground-color:#ffffff ;\r\n\t\t\tfont-family:Roboto;}\r\n\r\n\t\r\n\r\n\r\n\r\n\r\n\tbody #wpforms-536 .wpforms-submit-container .wpforms-submit, body #wpforms-536 .wpforms-field-pagebreak button.wpforms-page-button {\r\n\t\tbackground-color:#dd9933 ;\t\tborder-width: 0px;\t}\r\n\r\n\tbody #wpforms-536 .wpforms-submit-container .wpforms-submit:hover, body #wpforms-536 .wpforms-field-pagebreak button.wpforms-page-button:hover {\r\n\t\t\t}\r\n\r\n\tbody #wpforms-536 .wpforms-submit-container,\r\n\tbody #wpforms-536 .wpforms-field-pagebreak .wpforms-pagebreak-left{\r\n\t\t}\r\n\r\n\r\n\r\n\r\n\r\n\r\n\tbody #wpforms-536 .wpforms-form .wpforms-field textarea {\r\n\t\t\t\t\tborder-width: 1px;\t}\r\n\r\n \r\n\r\n\tbody #wpforms-536 .wpforms-form .wpforms-field select {\r\n\r\n\t\t\r\n\t\tborder-width: 1px;\t}\r\n\r\n\t\/* dropdown styles on modern background *\/\r\n\tbody #wpforms-536 .wpforms-form .wpforms-field-select-style-modern .choices__inner{\r\n\t\t\t\t\r\n\t}\r\n\r\n\t\/* background color on modern dropdown *\/\r\n\t\r\n\r\n\r\n\r\n \r\n\tbody #wpforms-confirmation-536  {\r\n\r\n\t\t\t\tborder-width: 1px;\t}\r\n\r\n\tbody #wpforms-confirmation-536 p{\r\n\t\ttext-transform: uppercase;\r\n\t\ttext-decoration: underline;\r\n\t\tcolor: inherit;\r\n\t}\r\n\r\n\/* Styling for Tablets *\/\r\n@media only screen and (max-width: 800px) and (min-width:481px) {\r\n\t\r\n\r\n\r\n\r\n}\r\n\r\n@media only screen and (max-width: 480px){\r\n\t\r\n\r\n\r\n\r\n}\r\n\/*Option to add custom CSS *\/\r\n\r\n\r\n\r\n\t\t<\/style>\r\n\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-536\"><form id=\"wpforms-form-536\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"536\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/136\" data-token=\"81052e36145e3e9579dfd1c9a00c6407\" data-token-time=\"1778675371\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-536-field_9-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"9\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-536-field_9\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][9][first]\" aria-errormessage=\"wpforms-536-field_9-error\" required><label for=\"wpforms-536-field_9\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-536-field_9-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][9][last]\" aria-errormessage=\"wpforms-536-field_9-last-error\" required><label for=\"wpforms-536-field_9-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-536-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-536-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-536-field_1-error\" required><\/div><div id=\"wpforms-536-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_6\">Motorcycle Brand and Model <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-536-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-536-field_6-error\" required><\/div><div id=\"wpforms-536-field_11-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_11\">Build Year <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-536-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" aria-errormessage=\"wpforms-536-field_11-error\" required><\/div><div id=\"wpforms-536-field_12-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_12\">Order Number<\/label><input type=\"text\" id=\"wpforms-536-field_12\" class=\"wpforms-field-medium\" name=\"wpforms[fields][12]\" aria-errormessage=\"wpforms-536-field_12-error\" ><\/div><div id=\"wpforms-536-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_2\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-536-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-536-field_2-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6Le4ZCUoAAAAACcntGrUa-SA3QveZytEvbs_v3Jt\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"536\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/pages\/136\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-536\" class=\"wpforms-submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/motolumino.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contact usLeave your message here and we will reply to you shortly<style id=\"wpforms-css-vars-536\">\n\t\t\t\t#wpforms-536 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style>\r\n<style type=\"text\/css\">\r\n@import url('https:\/\/fonts.googleapis.com\/css?family=Roboto');\r\n\r\n\r\nbody #wpforms-536 {\r\n\t\tbackground-color:#ffffff ;\r\n\t\t\tfont-family:Roboto;}\r\n\r\n\t\r\n\r\n\r\n\r\n\r\n\tbody #wpforms-536 .wpforms-submit-container .wpforms-submit, body #wpforms-536 .wpforms-field-pagebreak button.wpforms-page-button {\r\n\t\tbackground-color:#dd9933 ;\t\tborder-width: 0px;\t}\r\n\r\n\tbody #wpforms-536 .wpforms-submit-container .wpforms-submit:hover, body #wpforms-536 .wpforms-field-pagebreak button.wpforms-page-button:hover {\r\n\t\t\t}\r\n\r\n\tbody #wpforms-536 .wpforms-submit-container,\r\n\tbody #wpforms-536 .wpforms-field-pagebreak .wpforms-pagebreak-left{\r\n\t\t}\r\n\r\n\r\n\r\n\r\n\r\n\r\n\tbody #wpforms-536 .wpforms-form .wpforms-field textarea {\r\n\t\t\t\t\tborder-width: 1px;\t}\r\n\r\n \r\n\r\n\tbody #wpforms-536 .wpforms-form .wpforms-field select {\r\n\r\n\t\t\r\n\t\tborder-width: 1px;\t}\r\n\r\n\t\/* dropdown styles on modern background *\/\r\n\tbody #wpforms-536 .wpforms-form .wpforms-field-select-style-modern .choices__inner{\r\n\t\t\t\t\r\n\t}\r\n\r\n\t\/* background color on modern dropdown *\/\r\n\t\r\n\r\n\r\n\r\n \r\n\tbody #wpforms-confirmation-536  {\r\n\r\n\t\t\t\tborder-width: 1px;\t}\r\n\r\n\tbody #wpforms-confirmation-536 p{\r\n\t\ttext-transform: uppercase;\r\n\t\ttext-decoration: underline;\r\n\t\tcolor: inherit;\r\n\t}\r\n\r\n\/* Styling for Tablets *\/\r\n@media only screen and (max-width: 800px) and (min-width:481px) {\r\n\t\r\n\r\n\r\n\r\n}\r\n\r\n@media only screen and (max-width: 480px){\r\n\t\r\n\r\n\r\n\r\n}\r\n\/*Option to add custom CSS *\/\r\n\r\n\r\n\r\n\t\t<\/style>\r\n\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-536\"><form id=\"wpforms-form-536\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"536\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/136\" data-token=\"81052e36145e3e9579dfd1c9a00c6407\" data-token-time=\"1778675371\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-536-field_9-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"9\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-536-field_9\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][9][first]\" aria-errormessage=\"wpforms-536-field_9-error\" required><label for=\"wpforms-536-field_9\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-536-field_9-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][9][last]\" aria-errormessage=\"wpforms-536-field_9-last-error\" required><label for=\"wpforms-536-field_9-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-536-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-536-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-536-field_1-error\" required><\/div><div id=\"wpforms-536-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_6\">Motorcycle Brand and Model <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-536-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-536-field_6-error\" required><\/div><div id=\"wpforms-536-field_11-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_11\">Build Year <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-536-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" aria-errormessage=\"wpforms-536-field_11-error\" required><\/div><div id=\"wpforms-536-field_12-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_12\">Order Number<\/label><input type=\"text\" id=\"wpforms-536-field_12\" class=\"wpforms-field-medium\" name=\"wpforms[fields][12]\" aria-errormessage=\"wpforms-536-field_12-error\" ><\/div><div id=\"wpforms-536-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-536-field_2\">Message <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-536-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-536-field_2-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6Le4ZCUoAAAAACcntGrUa-SA3QveZytEvbs_v3Jt\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"536\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/pages\/136\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-536\" class=\"wpforms-submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/motolumino.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/pages\/136"}],"collection":[{"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":13,"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/pages\/136\/revisions"}],"predecessor-version":[{"id":647,"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/pages\/136\/revisions\/647"}],"wp:attachment":[{"href":"https:\/\/motolumino.com\/fr\/wp-json\/wp\/v2\/media?parent=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}